{"id":4360,"date":"2020-07-27T23:27:54","date_gmt":"2020-07-27T23:27:54","guid":{"rendered":"https:\/\/tilosamericas.com\/?p=4360"},"modified":"2020-07-27T23:27:54","modified_gmt":"2020-07-27T23:27:54","slug":"ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2","status":"publish","type":"post","link":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/","title":{"rendered":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS"},"content":{"rendered":"<p>En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con\u00a0<strong>un descuento especial\u00a0<\/strong><strong>durante el mes de Agosto 2020.<\/strong><\/p>\n<p><em>TILOS es la herramienta preferida por empresas globales en las industrias de energ\u00eda e infraestructura para planificaci\u00f3n y ejecuci\u00f3n de proyectos lineales.<\/em><\/p>\n<p>A diferencia de MS Project o Primavera P6, los diagramas de Tiempo \u2013Distancia de TILOS muestran\u00a0<strong>no solo fechas de actividades<\/strong>, sino tambi\u00e9n la ubicaci\u00f3n de las mismas. Como resultado, los planificadores en TILOS experimentan\u00a0<strong>menos incertidumbre al controlar sus actividades y sus reportes de\u00a0<\/strong><strong>avances se muestran con mayor exactitud.<\/strong><\/p>\n<p>Invitamos a nuestros clientes a experimentar los beneficios del trabajo desde casa cuando sea posible, y a la vez a tomar ventaja de esta situaci\u00f3n para aprovechar este valioso tiempo invirtiendo una parte de el en capacitaci\u00f3n.<\/p>\n<p><strong>Es un buen momento para posiciones como:<\/strong><\/p>\n<p>\uf0b7 Gerentes de Proyecto<br \/>\n\uf0b7 Planificadores<br \/>\n\uf0b7 Coordinadores de Construcci\u00f3n<br \/>\n\uf0b7 Jefes de Control de Proyecto<\/p>\n<p><strong>Para invertir en mejorar habilidades para sus equipos de trabajo a un costo<\/strong><br \/>\n<strong>accesible.<br \/>\n<\/strong><br \/>\nEsta promoci\u00f3n es v\u00e1lida desde Abril 23\/2020 hasta Agosto 31\/2020.<\/p>\n<p>Cursos de Entrenamiento online en TILOS, ya sea B\u00e1sico o Avanzado:<\/p>\n<p><strong>\uf0b7 25% de descuento para grupos de 2 o m\u00e1s personas.<\/strong><br \/>\n<strong>\uf0b7 10% de descuento para 1 persona.<br \/>\n<\/strong><br \/>\n<a href=\"https:\/\/tilosamericas.com\/es\/contact\/\">Cont\u00e1ctenos para m\u00e1s informaci\u00f3n.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con\u00a0un descuento especial\u00a0durante el mes de Agosto 2020. TILOS es la herramienta preferida por empresas globales en las industrias de energ\u00eda e infraestructura para planificaci\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-4360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -<\/title>\n<meta name=\"description\" content=\"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -\" \/>\n<meta property=\"og:description\" content=\"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tilos Americas\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-27T23:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS-1030x578.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"lorne.duncan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lorne.duncan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/\"},\"author\":{\"name\":\"lorne.duncan\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/#\\\/schema\\\/person\\\/0fd860950517ded5c54863eb53b93264\"},\"headline\":\"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS\",\"datePublished\":\"2020-07-27T23:27:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/\"},\"wordCount\":243,\"image\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tilosamericas.com\\\/wp-content\\\/uploads\\\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/\",\"url\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/\",\"name\":\"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tilosamericas.com\\\/wp-content\\\/uploads\\\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png\",\"datePublished\":\"2020-07-27T23:27:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/#\\\/schema\\\/person\\\/0fd860950517ded5c54863eb53b93264\"},\"description\":\"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tilosamericas.com\\\/wp-content\\\/uploads\\\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png\",\"contentUrl\":\"https:\\\/\\\/tilosamericas.com\\\/wp-content\\\/uploads\\\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png\",\"width\":2872,\"height\":1612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tilosamericas.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/#website\",\"url\":\"https:\\\/\\\/tilosamericas.com\\\/\",\"name\":\"Tilos Americas\",\"description\":\"Proven Experience. You Project Deserves.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tilosamericas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tilosamericas.com\\\/#\\\/schema\\\/person\\\/0fd860950517ded5c54863eb53b93264\",\"name\":\"lorne.duncan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g\",\"caption\":\"lorne.duncan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -","description":"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/","og_locale":"es_ES","og_type":"article","og_title":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -","og_description":"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.","og_url":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/","og_site_name":"Tilos Americas","article_published_time":"2020-07-27T23:27:54+00:00","og_image":[{"width":1030,"height":578,"url":"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS-1030x578.png","type":"image\/png"}],"author":"lorne.duncan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lorne.duncan","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#article","isPartOf":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/"},"author":{"name":"lorne.duncan","@id":"https:\/\/tilosamericas.com\/#\/schema\/person\/0fd860950517ded5c54863eb53b93264"},"headline":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS","datePublished":"2020-07-27T23:27:54+00:00","mainEntityOfPage":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/"},"wordCount":243,"image":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/","url":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/","name":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS -","isPartOf":{"@id":"https:\/\/tilosamericas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#primaryimage"},"image":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png","datePublished":"2020-07-27T23:27:54+00:00","author":{"@id":"https:\/\/tilosamericas.com\/#\/schema\/person\/0fd860950517ded5c54863eb53b93264"},"description":"En respuesta a la situaci\u00f3n actual por el COVID19 y recomendaci\u00f3n de autoridades a permanecer en casa, el equipo de Petroglyph est\u00e1 ofreciendo Cursos de Entrenamiento online en TILOS con un descuento especial durante el mes de Mayo 2020.","breadcrumb":{"@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#primaryimage","url":"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png","contentUrl":"https:\/\/tilosamericas.com\/wp-content\/uploads\/Ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-TILOS.png","width":2872,"height":1612},{"@type":"BreadcrumbList","@id":"https:\/\/tilosamericas.com\/es\/ahorre-hasta-un-25-en-cursos-online-de-entrenaimento-en-tilos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tilosamericas.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ahorre hasta un 25% en cursos online de entrenaimento en TILOS"}]},{"@type":"WebSite","@id":"https:\/\/tilosamericas.com\/#website","url":"https:\/\/tilosamericas.com\/","name":"Tilos Americas","description":"Proven Experience. You Project Deserves.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tilosamericas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tilosamericas.com\/#\/schema\/person\/0fd860950517ded5c54863eb53b93264","name":"lorne.duncan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56e45dca22c3f63d0040137c6270cc66936efee1feda3dd8913303439df071c5?s=96&d=mm&r=g","caption":"lorne.duncan"}}]}},"_links":{"self":[{"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/posts\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/comments?post=4360"}],"version-history":[{"count":0,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/posts\/4360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/media\/4356"}],"wp:attachment":[{"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/media?parent=4360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/categories?post=4360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilosamericas.com\/es\/wp-json\/wp\/v2\/tags?post=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}